{"id":363,"date":"2020-04-28T16:45:19","date_gmt":"2020-04-28T14:45:19","guid":{"rendered":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/?p=363"},"modified":"2020-04-28T16:54:21","modified_gmt":"2020-04-28T14:54:21","slug":"leben-und-das-leben-einen-leben-lassen","status":"publish","type":"post","link":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/","title":{"rendered":"Leben und das Leben einen leben lassen&#8230;"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185820-1024x576.jpg\" alt=\"\" class=\"wp-image-368\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185820-1024x576.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185820-300x169.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185820-768x432.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185820-900x506.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185820.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Name der Fluggesellschaft: &#8222;Vamos&#8220; &#8211; &#8222;Gehen wir&#8220;<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Am Samstag dem 28.03.2020, vor genau einem Monat war es so weit.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"> Um kurz nach zw\u00f6lf betraten wir wieder deutschen Boden am Frankfurter Flughafen. War das so geplant? Ich glaube nicht&#8230; Ich bin bestimmt nicht der erste damit, dem dieser Ausnahmezustand einen fetten Strich durch die Rechnung macht. Bei uns Auslandsvolont\u00e4ren hat das sehr sp\u00fcrbare und schlagartige Ver\u00e4nderungen ausgel\u00f6st&#8230; Ich erz\u00e4hl euch wie das war.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es war der 16.03.2020, als vom Bundesministerium f\u00fcr wirtschaftliche Zusammenarbeit (BMZ), die klare Entscheidung bekanntgegeben wurde, so bald wie m\u00f6glich alle sich im Ausland befindenden Volont\u00e4re wieder heimzuholen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Na toll.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"> Das war genau das, was wir alle als das unvorstellbarste Szenario ausgemalt haben. Ich hatte schon zwei Tage zuvor von einer anderen Volont\u00e4rin, die auch einen <a href=\"https:\/\/www.donboscovolunteers.de\/\">Freiwilligendienst<\/a> in <a href=\"https:\/\/strassenkinder.de\/laender\/lateinamerika\/bolivien-strassenkinderzentrum\/\">Santa Cruz<\/a> macht, geh\u00f6rt, dass sie von ihrer Organisation zur\u00fcckgeholt wird. Das konnte ich erst mal nicht glauben, da die Situation sich in <a href=\"https:\/\/multimedia.strassenkinder.de\/bolivien\">Bolivien<\/a> noch lange nicht so zugespitzt hatte, wie es zum Beispiel in Deutschland der Fall war. Zu diesem Zeitpunkt gab es gerade mal zwei best\u00e4tigte F\u00e4lle des Virus im ganzen Land. Daher hat sich also die Anweisung, uns in das Land zur\u00fcckzufliegen, wo derzeit weitaus schlimmere Zust\u00e4nde herrschten, erst mal unverst\u00e4ndlich angeh\u00f6rt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich kann mich noch an ein Seminar in unserer Vorbereitungszeit auf den Freiwilligendienst erinnern, wo wir vor ziemlich genau einem Jahr das Thema &#8222;R\u00fcckholaktionen im Falle von pl\u00f6tzlichen Kriegs- oder Krisensituationen&#8220; behandelten. Hm&#8230; da dachte man sich damals als angehender, frischer, unerfahrener Freiwilliger, dass das halt auch nur obligatorisch in unserer Vorbereitung behandelt werden muss&#8230; Aber mal ganz ehrlich &#8211; niemand h\u00e4tte zu dem damaligen Zeitpunkt wirklich damit gerechnet.  Ich kann mich da noch selbst dran erinnern, f\u00fcr wie unwahrscheinlich ich dieses Szenario eingestuft habe&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit der offiziellen Kundgebung dieser R\u00fcckholma\u00dfnahme war es dann aber tats\u00e4chlich so weit. Die Stimmung im Volont\u00e4rshaus? &#8211; Kann man sich vielleicht vorstellen. &#8211; Alle nicht so gut drauf um es mal so auszudr\u00fccken&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Hat denn irgendjemand einen Plan?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"> Nein. Niemand. Das war das Spannende bei der Sache. Das Bundesministerium in Deutschland hatte n\u00e4mlich nur bekanntgegeben, DASS wir schnellstm\u00f6glich zur\u00fcckm\u00fcssen, aber nicht WIE. Das wurde dann n\u00e4mlich zun\u00e4chst unserer Organisation und uns selbst \u00fcberlassen. Man muss sich vorstellen, dass es in den folgenden Tagen von Neuigkeiten nur so gehagelt hat. Hier die Versch\u00e4rfung der Ausgangssperre in Bolivien und der darauf folgende Aufruf zu Hamsterk\u00e4ufen, dort die Ank\u00fcndigung einer geplanten R\u00fcckholaktion aller Deutschen aus dem Ausland&#8230; ach ja, da muss noch ein Formular ausgef\u00fcllt werden&#8230; Weiterhin h\u00f6ren wir in immer geringeren Abst\u00e4nden die Schlie\u00dfung jeglicher internationaler Flugh\u00e4fen in S\u00fcdamerika, bis es dann auch in Bolivien so weit war. Dann hatte nur noch Sao Paolo in Brasilien als einziger Flughafen auf dem gesamten Kontinent eine Flugverbindung nach Europa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber keiner wusste, wie lange das noch der Fall war&#8230; wir mussten also abw\u00e4gen, ob wir mit irgendeinem Bus noch von Santa Cruz bis nach Sao Paolo kommen w\u00fcrden, bevor uns diese M\u00f6glichkeit dann auch gestrichen wird, oder ob wir auf weitere Infos vom Ausw\u00e4rtigen Amt bez\u00fcglich eines offiziellen R\u00fcckholflugs aus Deutschland warten sollten. So h\u00e4mmerten die Infos in einem sehr spannenden Live-Ticker auf uns ein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Dann irgendwann,<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;nach einer Woche regem Kontakt mit unser Organisation und der Deutschen Botschaft Bolivien, Gespr\u00e4chen mit dem Flughafen in Sao Paolo, zahlreichen Anmeldungsversuchen bei verschiedenen R\u00fcckholaktionen und obendrauf noch einigen emotionalen Krisensitzungen in unserer Wohngemeinschaft, war es endlich so weit. Es kam die (einigerma\u00dfen) sichere Info, dass am Freitagabend, den 27.03. ein Riesenflieger nach Santa Cruz geschickt w\u00fcrde, der alle Deutschen Urlauber und Freiwilligen aus ganz Bolivien abholen sollte. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mitgeteilt wurde uns aber in der selben Mail ebenfalls von der Botschaft, dass nicht allen ein Sitzplatz garantiert werden k\u00f6nne. Freiwillige h\u00e4tten aber Vorrang, da sie ja unter der Obhut des Staates im Ausland w\u00e4ren. Nichtsdestotrotz wussten wir, bis wir dann letztendlich im Flieger sa\u00dfen, nicht, ob wir einen Platz bekommen w\u00fcrden. Es waren tats\u00e4chlich schon einige deutsche, die sich da am Abflugtag aus allen m\u00f6glichen Orten in Bolivien herkommend an diesem einen Flughafen in Santa Cruz zusammenkamen, wie wir sp\u00e4ter herausfinden sollten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Was aber f\u00fcr mich w\u00e4hrend dieser hektischen Tage nat\u00fcrlich genauso hohe Priorit\u00e4t hatte, war auch ein einigerma\u00dfen gelungener Abschied von dem Projekt und den Jugendlichen, mit denen ich immerhin die letzten sieben Monate verbracht habe. Das habe ich aber nach eigenen Angaben, der Situation entsprechend ganz gut hinbekommen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200325_111632-1024x576.jpg\" alt=\"\" class=\"wp-image-370\" width=\"645\" height=\"363\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200325_111632-1024x576.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200325_111632-300x169.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200325_111632-768x432.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200325_111632-900x506.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200325_111632.jpg 1280w\" sizes=\"auto, (max-width: 645px) 100vw, 645px\" \/><figcaption>ein letztes mal richtig Spa\u00df haben mit den Jungs<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Auch f\u00fcr uns war der Plan dann recht bald klar &#8211; <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">nach der Verabschiedung hie\u00df es dann Zeug zusammenpacken und raus aus dem Haus &#8211; letzteres l\u00e4sst sich wirklich nicht viel anders beschreiben&#8230; als ich mich n\u00e4mlich am Freitagmorgen von meinen Jungs im Techo Pinardi verabschiedet hatte, kam die Neuigkeit, dass uns ab zw\u00f6lf Uhr mittags niemand mehr zum Flughafen bringen k\u00f6nne, da totale Ausgangssperre herrschte. Nicht mal unser Koordinator konnte sich eine Erlaubnis f\u00fcr nach zw\u00f6lf Uhr klar machen. Jetzt stelle man sich vor, ich komme ca. um 10.30 Uhr von meiner Verabschiedung nach Hause &#8211; die anderen Volont\u00e4re waren schon ein bisschen am Haus aufr\u00e4umen &#8211; aber mit mir kommt unser Koordinator mit der Nachricht, wir m\u00fcssten sofort abfahren, sonst bekomme er ziemlich Stress mit der Polizei&#8230; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Jagut,&#8230;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;das h\u00f6rte sich ziemlich eindeutig an und so begann die am meisten \u00fcberhetzte Abreise und Wohnungs\u00fcbergabe, die ich bis jetzt je erlebt habe. Es hie\u00df ab da nur noch &#8222;Apurrense, ya no nos queda tiempo&#8220; &#8211; &#8222;Beeilt euch, wir haben keine Zeit mehr!&#8220; Wir waren wirklich am Limit und zu all unserem Packstress war noch die Nachricht gekommen, dass wir im Flieger auf Grund dessen begrenzten Lagerkapazit\u00e4ten nur maximal ein Aufgabegep\u00e4ckst\u00fcck mit 23 kg und ein Handgep\u00e4ck bis 5 Kilo mitnehmen konnten. Doof nur, dass wir von allem mehr zu bieten hatten. So kam es, dass ich einen gro\u00dfen Koffer mit einigen meiner Habseligkeiten in Santa Cruz de la Sierra stehen lassen musste &#8211; wer wei\u00df, ob ich den nochmal wieder sehe&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dann\nwar es so weit &#8211; Das Autodach zum brechen vollgepackt mit\nVolont\u00e4rskoffern und innen drin acht Leute im Sechssitzer-Jeep.\nLetzteres war f\u00fcr uns keine gro\u00dfe Herausforderung mehr, da wir\ngrunds\u00e4tzlich gerne mal zu siebt oder mehr in dem ein oder anderen\nTaxi fuhren. \n<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_111427-1024x576.jpg\" alt=\"\" class=\"wp-image-373\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_111427-1024x576.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_111427-300x169.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_111427-768x432.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_111427-900x506.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_111427.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>&#8230;unser Flughafenmobil<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als wir dann um halb zw\u00f6lf am Flughafen &#8222;Viru Viru&#8220; in Santa Cruz ankamen und ich mich innerlich so langsam von meiner Zeit in Santa Cruz verabschiedete, wurde mir erst klar, dass wir noch nicht so gleich einchecken konnten, denn unsere Maschine sollte erst um elf Uhr abends abheben&#8230; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um 14 Uhr fing dann das Check-in-Chaos an, denn so einen Sonderflug zu koordinieren und dabei noch zu entscheiden, wer nun mit darf und wer nicht, stellte sich als nicht ganz einfach heraus. Also hie\u00df es f\u00fcr uns Schlange stehen&#8230; Oder sitzen bzw. liegen. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_170017-1024x768.jpg\" alt=\"\" class=\"wp-image-372\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_170017-1024x768.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_170017-300x225.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_170017-768x576.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_170017-900x675.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_170017.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">F\u00fcnf volle Stunden&#8230;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;w\u00e4hrend welcher sich 500 Menschen fragten, ob sie denn heute wirklich in einem Flieger mit 450 Pl\u00e4tzen mitkommen w\u00fcrden. Am Ende stellte sich heraus, dass tats\u00e4chlich nur 450 dieser hei\u00df begehrten Stoffsitze vergeben wurden und so mussten die circa \u00fcbrigen 50 Leute auf den n\u00e4chsten Flieger warten, der vielleicht in der n\u00e4chsten Woche kommen w\u00fcrde.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_165050-576x1024.jpg\" alt=\"\" class=\"wp-image-371\" width=\"294\" height=\"522\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_165050-576x1024.jpg 576w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_165050-169x300.jpg 169w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_165050.jpg 720w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/><figcaption>die &#8222;Schlange&#8220;<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Aber wir Volont\u00e4re waren alle drin.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Was f\u00fcr ein hervorragendes Gef\u00fchl, nach dieser ewigen Nervenfolter einmal Klartext zu haben. Zuvor wurden wir durch Passkontrolle, Migrationsbeh\u00f6rde und Sicherheitsschranke gejagt, immer wieder mit der Nachricht im Nacken, dass wir uns beeilen sollten, weil wir zu den letzten geh\u00f6rten. Die Abflugzeit wurde auf 19 Uhr vorverlegt und es gab wirklich Stress, sodass ich mich noch erinnern kann, wie ich im Laufschritt die riesige Fliegerteppe hinaufrannte, um noch mitzukommen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185821-1024x576.jpg\" alt=\"\" class=\"wp-image-369\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185821-1024x576.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185821-300x169.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185821-768x432.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185821-900x506.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185821.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>ja, ich bin wirklich gerannt<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_192612-1024x576.jpg\" alt=\"\" class=\"wp-image-374\" width=\"580\" height=\"326\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_192612-1024x576.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_192612-300x169.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_192612-768x432.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_192612-900x506.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_192612.jpg 1280w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption>Abflug.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Und dann ging es los.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Am Freitagabend, recht p\u00fcnktlich um 19:05 Uhr setzte sich dieser riesige Vogel in Bewegung in Richtung Heimat. Vollgestopft bis zum letzten Platz, erhob er sich mit viel M\u00fche in die L\u00fcfte, von einer Startbahn, die keine zehn Meter k\u00fcrzer h\u00e4tte sein d\u00fcrfen&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ja,\nalles war so ein bisschen knapp &#8211; vom Anlauf, den unser Flieger\ngenommen hat, bis zu meinen sieben Monaten in Bolivien, die ja\neigentlich ein Jahr sein sollten&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber eins haben diese beiden Tatsachen gemeinsam: <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Es hat gepasst. <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Genau so und nicht anders. Daheim angekommen l\u00e4uft das Leben weiter &#8211; ob ich jetzt sieben Monate oder zw\u00f6lf weg war, &#8211; ich habe ja ein zu Hause. Und eigentlich konnte auch wieder niemand etwas daf\u00fcr, dass es so gelaufen ist, wie es eben gelaufen ist&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ja, ich werde das schon vermissen&#8230;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200325_155213-576x1024.jpg\" alt=\"\" class=\"wp-image-375\" width=\"322\" height=\"572\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200325_155213-576x1024.jpg 576w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200325_155213-169x300.jpg 169w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200325_155213.jpg 720w\" sizes=\"auto, (max-width: 322px) 100vw, 322px\" \/><figcaption>&#8230;die Zeit mit den Jungs aus dem Techo&#8230;<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200319_193437-1024x576.jpg\" alt=\"\" class=\"wp-image-376\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200319_193437-1024x576.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200319_193437-300x169.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200319_193437-768x432.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200319_193437-900x506.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200319_193437.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>&#8230;das &#8211; mal mehr &amp; mal weniger &#8211; gute Essen \ud83d\ude42 &#8230;<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200320_181740-1024x576.jpg\" alt=\"\" class=\"wp-image-377\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200320_181740-1024x576.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200320_181740-300x169.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200320_181740-768x432.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200320_181740-900x506.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200320_181740.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>&#8230;so richtige Volont\u00e4rsarbeit&#8230;<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200323_192234-1024x576.jpg\" alt=\"\" class=\"wp-image-383\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200323_192234-1024x576.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200323_192234-300x169.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200323_192234-768x432.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200323_192234-900x506.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200323_192234.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>&#8230;die gemeinsame Zeit in der WG&#8230;<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200320_090640-1024x576.jpg\" alt=\"\" class=\"wp-image-378\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200320_090640-1024x576.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200320_090640-300x169.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200320_090640-768x432.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200320_090640-900x506.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200320_090640.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>&#8230;diese Beiden Kollegen, die mich bei der Arbeit unterst\u00fctzt haben&#8230;<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200324_225154-576x1024.jpg\" alt=\"\" class=\"wp-image-379\" width=\"350\" height=\"623\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200324_225154-576x1024.jpg 576w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200324_225154-169x300.jpg 169w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200324_225154.jpg 720w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><figcaption>&#8230;sowie das teilweise dreckige und schwierige Stra\u00dfenleben in Santa Cruz, womit ich jetzt einige Erfahrungen gemacht habe&#8230;<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200324_231550-576x1024.jpg\" alt=\"\" class=\"wp-image-380\" width=\"354\" height=\"630\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200324_231550-576x1024.jpg 576w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200324_231550-169x300.jpg 169w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200324_231550.jpg 720w\" sizes=\"auto, (max-width: 354px) 100vw, 354px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das sind ein paar Gedanken, die ich mir jetzt r\u00fcckblickend auf meine wundervolle Zeit auf der anderen Seite der Welt so mache. Nat\u00fcrlich gibt es Momente wo ich mir denke, was ich vielleicht noch alles erlebt h\u00e4tte&#8230; aber zur Zeit kann ich daran nichts \u00e4ndern. Egal &#8211; ich werde auf jeden Fall noch ein mal zur\u00fcckkommen. Das steht fest. Ob ich euch davon dann auch erz\u00e4hlen kann, wei\u00df ich noch nicht.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200323_090214-min-1-575x1024.jpg\" alt=\"\" class=\"wp-image-386\" width=\"236\" height=\"420\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200323_090214-min-1-575x1024.jpg 575w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200323_090214-min-1-169x300.jpg 169w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200323_090214-min-1.jpg 719w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/><figcaption>Hier noch eine sch\u00f6ne Blume.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~~<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Dieser Blog endet hier erst einmal. <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ich bin sehr froh, von meinen Erfahrungen, den Sorgen sowie den sch\u00f6nen Momenten etwas mitteilen zu k\u00f6nnen, denn ich halte es jetzt umso mehr f\u00fcr wichtig, sich in andere Lebensweisen und Situationen hineinversetzen zu versuchen, um nicht zu sehr in der eigenen, beschr\u00e4nkten Komfortzone stecken zu bleiben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In diesem Sinne &#8211; vielleicht auf ein andermal &#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">~  Macht\u00b4s gut &#8211; Es war mir eine Ehre ~<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Euer Gabriel<\/p>","protected":false},"excerpt":{"rendered":"<p>Am Samstag dem 28.03.2020, vor genau einem Monat war es so weit. Um kurz nach zw\u00f6lf betraten wir wieder deutschen Boden am Frankfurter Flughafen. War das so geplant? Ich glaube nicht&#8230; Ich bin bestimmt nicht der erste damit, dem dieser Ausnahmezustand einen fetten Strich durch die Rechnung macht. Bei uns Auslandsvolont\u00e4ren hat das sehr sp\u00fcrbare [&hellip;]<\/p>\n","protected":false},"author":21652,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[49,14,22,15,34],"class_list":["post-363","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-abreise","tag-bolivien","tag-proyecto-don-bosco","tag-santa-cruz","tag-volontaere"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leben und das Leben einen leben lassen... - Ich bin dann mal raus von zu Haus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leben und das Leben einen leben lassen... - Ich bin dann mal raus von zu Haus\" \/>\n<meta property=\"og:description\" content=\"Am Samstag dem 28.03.2020, vor genau einem Monat war es so weit. Um kurz nach zw\u00f6lf betraten wir wieder deutschen Boden am Frankfurter Flughafen. War das so geplant? Ich glaube nicht&#8230; Ich bin bestimmt nicht der erste damit, dem dieser Ausnahmezustand einen fetten Strich durch die Rechnung macht. Bei uns Auslandsvolont\u00e4ren hat das sehr sp\u00fcrbare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/\" \/>\n<meta property=\"og:site_name\" content=\"Ich bin dann mal raus von zu Haus\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-28T14:45:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-28T14:54:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185820-1024x576.jpg\" \/>\n<meta name=\"author\" content=\"Gabriel Booms\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Booms\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/04\\\/28\\\/leben-und-das-leben-einen-leben-lassen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/04\\\/28\\\/leben-und-das-leben-einen-leben-lassen\\\/\"},\"author\":{\"name\":\"Gabriel Booms\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/#\\\/schema\\\/person\\\/1a683864941695e1f0cc7bf11766a30a\"},\"headline\":\"Leben und das Leben einen leben lassen&#8230;\",\"datePublished\":\"2020-04-28T14:45:19+00:00\",\"dateModified\":\"2020-04-28T14:54:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/04\\\/28\\\/leben-und-das-leben-einen-leben-lassen\\\/\"},\"wordCount\":1723,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/04\\\/28\\\/leben-und-das-leben-einen-leben-lassen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/wp-content\\\/uploads\\\/sites\\\/21591\\\/2020\\\/04\\\/20200327_185820-1024x576.jpg\",\"keywords\":[\"Abreise\",\"Bolivien\",\"Proyecto Don Bosco\",\"Santa Cruz#\",\"Volont\u00e4re\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/04\\\/28\\\/leben-und-das-leben-einen-leben-lassen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/04\\\/28\\\/leben-und-das-leben-einen-leben-lassen\\\/\",\"url\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/04\\\/28\\\/leben-und-das-leben-einen-leben-lassen\\\/\",\"name\":\"Leben und das Leben einen leben lassen... - Ich bin dann mal raus von zu Haus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/04\\\/28\\\/leben-und-das-leben-einen-leben-lassen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/04\\\/28\\\/leben-und-das-leben-einen-leben-lassen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/wp-content\\\/uploads\\\/sites\\\/21591\\\/2020\\\/04\\\/20200327_185820-1024x576.jpg\",\"datePublished\":\"2020-04-28T14:45:19+00:00\",\"dateModified\":\"2020-04-28T14:54:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/#\\\/schema\\\/person\\\/1a683864941695e1f0cc7bf11766a30a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/04\\\/28\\\/leben-und-das-leben-einen-leben-lassen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/04\\\/28\\\/leben-und-das-leben-einen-leben-lassen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/04\\\/28\\\/leben-und-das-leben-einen-leben-lassen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/wp-content\\\/uploads\\\/sites\\\/21591\\\/2020\\\/04\\\/20200327_185820.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/wp-content\\\/uploads\\\/sites\\\/21591\\\/2020\\\/04\\\/20200327_185820.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/04\\\/28\\\/leben-und-das-leben-einen-leben-lassen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leben und das Leben einen leben lassen&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/#website\",\"url\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/\",\"name\":\"Ich bin dann mal raus von zu Haus\",\"description\":\"Ein Jahr in Bolivien\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/#\\\/schema\\\/person\\\/1a683864941695e1f0cc7bf11766a30a\",\"name\":\"Gabriel Booms\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92e27b1059f2d1de2c41fd06a37662ca44a4fa61c443eab6be7a8ead5e3d9b62?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92e27b1059f2d1de2c41fd06a37662ca44a4fa61c443eab6be7a8ead5e3d9b62?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92e27b1059f2d1de2c41fd06a37662ca44a4fa61c443eab6be7a8ead5e3d9b62?s=96&d=blank&r=g\",\"caption\":\"Gabriel Booms\"},\"description\":\"Buenos dias, Guten Tag oder Servus zusammen! Ich bin Gabriel Booms, 18 Jahre jung und fliege am 1. September 2019 f\u00fcr ein Jahr nach Santa Cruz de la Sierra in Bolivien. Das hier ist mein pers\u00f6nlicher Blog, in dem ich euch gerne hin und wieder mit frischen Neuigkeiten aus meinem Projekt in Bolivien versorgen m\u00f6chte. Wer gerne direkt mitbekommen will, wenn ich hier was poste, schreibt mir doch einfach einen Kommentar mit seiner E-Mail Adresse - dann nehme ich euch gerne in meinen Verteiler auf. Sch\u00f6n, dass ihr dabei seit - Euer Gabriel\",\"url\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/author\\\/bolivibooms\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leben und das Leben einen leben lassen... - Ich bin dann mal raus von zu Haus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/","og_locale":"de_DE","og_type":"article","og_title":"Leben und das Leben einen leben lassen... - Ich bin dann mal raus von zu Haus","og_description":"Am Samstag dem 28.03.2020, vor genau einem Monat war es so weit. Um kurz nach zw\u00f6lf betraten wir wieder deutschen Boden am Frankfurter Flughafen. War das so geplant? Ich glaube nicht&#8230; Ich bin bestimmt nicht der erste damit, dem dieser Ausnahmezustand einen fetten Strich durch die Rechnung macht. Bei uns Auslandsvolont\u00e4ren hat das sehr sp\u00fcrbare [&hellip;]","og_url":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/","og_site_name":"Ich bin dann mal raus von zu Haus","article_published_time":"2020-04-28T14:45:19+00:00","article_modified_time":"2020-04-28T14:54:21+00:00","og_image":[{"url":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185820-1024x576.jpg","type":"","width":"","height":""}],"author":"Gabriel Booms","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Gabriel Booms","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/#article","isPartOf":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/"},"author":{"name":"Gabriel Booms","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/#\/schema\/person\/1a683864941695e1f0cc7bf11766a30a"},"headline":"Leben und das Leben einen leben lassen&#8230;","datePublished":"2020-04-28T14:45:19+00:00","dateModified":"2020-04-28T14:54:21+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/"},"wordCount":1723,"commentCount":2,"image":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185820-1024x576.jpg","keywords":["Abreise","Bolivien","Proyecto Don Bosco","Santa Cruz#","Volont\u00e4re"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/","url":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/","name":"Leben und das Leben einen leben lassen... - Ich bin dann mal raus von zu Haus","isPartOf":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/#primaryimage"},"image":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185820-1024x576.jpg","datePublished":"2020-04-28T14:45:19+00:00","dateModified":"2020-04-28T14:54:21+00:00","author":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/#\/schema\/person\/1a683864941695e1f0cc7bf11766a30a"},"breadcrumb":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/#primaryimage","url":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185820.jpg","contentUrl":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/04\/20200327_185820.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/04\/28\/leben-und-das-leben-einen-leben-lassen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/"},{"@type":"ListItem","position":2,"name":"Leben und das Leben einen leben lassen&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/#website","url":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/","name":"Ich bin dann mal raus von zu Haus","description":"Ein Jahr in Bolivien","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/#\/schema\/person\/1a683864941695e1f0cc7bf11766a30a","name":"Gabriel Booms","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/92e27b1059f2d1de2c41fd06a37662ca44a4fa61c443eab6be7a8ead5e3d9b62?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/92e27b1059f2d1de2c41fd06a37662ca44a4fa61c443eab6be7a8ead5e3d9b62?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/92e27b1059f2d1de2c41fd06a37662ca44a4fa61c443eab6be7a8ead5e3d9b62?s=96&d=blank&r=g","caption":"Gabriel Booms"},"description":"Buenos dias, Guten Tag oder Servus zusammen! Ich bin Gabriel Booms, 18 Jahre jung und fliege am 1. September 2019 f\u00fcr ein Jahr nach Santa Cruz de la Sierra in Bolivien. Das hier ist mein pers\u00f6nlicher Blog, in dem ich euch gerne hin und wieder mit frischen Neuigkeiten aus meinem Projekt in Bolivien versorgen m\u00f6chte. Wer gerne direkt mitbekommen will, wenn ich hier was poste, schreibt mir doch einfach einen Kommentar mit seiner E-Mail Adresse - dann nehme ich euch gerne in meinen Verteiler auf. Sch\u00f6n, dass ihr dabei seit - Euer Gabriel","url":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/author\/bolivibooms\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/posts\/363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/users\/21652"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/comments?post=363"}],"version-history":[{"count":10,"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/posts\/363\/revisions"}],"predecessor-version":[{"id":389,"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/posts\/363\/revisions\/389"}],"wp:attachment":[{"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/media?parent=363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/categories?post=363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/tags?post=363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}