{"id":263,"date":"2020-01-17T19:44:03","date_gmt":"2020-01-17T18:44:03","guid":{"rendered":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/?p=263"},"modified":"2020-01-17T19:47:31","modified_gmt":"2020-01-17T18:47:31","slug":"weihnachtszeit-und-neujahr","status":"publish","type":"post","link":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/","title":{"rendered":"Weihnachtszeit und Neujahr &#8211; ich erz\u00e4hle euch mal wie das so war."},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191211-WA0004-1024x768.jpg\" alt=\"\" class=\"wp-image-271\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191211-WA0004-1024x768.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191211-WA0004-300x225.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191211-WA0004-768x576.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191211-WA0004-900x675.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191211-WA0004.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Guten\nmorgen, guten Mittag oder auch guten Abend liebe Leute,<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;mag sein, dass die Weihnachtszeit nun schon etwas her ist, aber daf\u00fcr bekommt ihr jetzt einen kleinen Einblick, wie man das Ganze hier in S\u00fcdamerika feiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich wei\u00df gar nicht mehr, ob und wem ich w\u00e4hrend der Vorweihnachtszeit alles schon erz\u00e4hlt habe, in wie wenig Weihnachtsstimmung ich selbst mich befand. Und das, obwohl man hier &#8211; wie es eben so \u00fcblich ist &#8211;  Plastikweihnachtsb\u00e4ume mit in Kunstschneemasse eingetauchten Zweigspitzen, singende Lichterketten wo das Auge hinreicht und das hier sowieso schon sehr beliebte koffeinhaltige Erfrischungsgetr\u00e4nk zu noch g\u00fcnstigeren Weihnachtsangeboten verkauft hat.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20200101-WA0025-1024x576.jpg\" alt=\"\" class=\"wp-image-270\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20200101-WA0025-1024x576.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20200101-WA0025-300x169.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20200101-WA0025-768x432.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20200101-WA0025-900x506.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20200101-WA0025.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>&#8230;unter anderem hier zu sehen: Der &#8222;Christbaum&#8220; in der Kirche<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch der Weihnachtsmann war, entgegen meiner Erwartung nicht in Badehose, sondern so wie man ihn kennt, dick eingepackt in warme Klamotten auf dem gro\u00dfen Stadtplatz vorzufinden. Man passt sich hier sehr an das klischeehafte Weihnachtsbild, so wie wir es gew\u00f6hnt sind an. Im Projekt war das f\u00fcr die Leute aber nat\u00fcrlich ganz normal und so ist die Vorfreude bei den Kindern und Jugendlichen auch dementsprechend gestiegen.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wir als Volont\u00e4re haben die Festtage weitestgehend in unseren Einrichtungen verbracht &#8211; <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ich fand die Bescherung, die wir schon nachmittags um 4, zusammen mit den Jungs und den Mitarbeitern, noch vor der Heiligabendmesse feierten sehr sch\u00f6n. Nat\u00fcrlich waren die meisten schon gespannt auf das, was der den M\u00f6glichkeiten entsprechend feierlich geschm\u00fcckte Festmalstisch versprach. Unter dem Christbaum haben wir die Geschenke hingestellt &#8211; f\u00fcr jeden gab es ein P\u00e4ckchen.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich hatte mich auch im Vorfeld gefragt, was man den Jungs als  &#8211; trotz allem auf Spendengelder angewiesene Einrichtung &#8211; schenken k\u00f6nnte&#8230; Da konnten so oder so nicht die Herzensw\u00fcnsche jedes einzelnen ber\u00fccksichtigt werden. Naja &#8211;  es gab f\u00fcr jeden ein P\u00e4ckchen mit sauberer, neuer Kleidung &#8211; und das bedeutet den Jungs hier tats\u00e4chlich zumindest f\u00fcr den Moment eine ganze Menge. Etwas sauberes zum Anziehen, geschweige denn eine gro\u00dfe Auswahl an Kleidung hat das Stra\u00dfenleben f\u00fcr die meisten n\u00e4mlich nicht zu bieten. Ich sehe immer wieder, wie die meist dreckigen Anziehsachen mehr funktional benutzt werden, als dass sie als &#8222;Statussymbol&#8220; getragen werden. Gerade deshalb sind die Jungs immer wieder froh, wenn sie etwas neues, schickes, stylisches als das Ihrige bezeichnen k\u00f6nnen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Aber in &#8222;Weihnachten&#8220; steckt ja bekanntlich mehr als nur die Geschenke &#8211; und das habe ich hier mehr als sonst immer mitbekommen. <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Danach bekam jeder Junge eine S\u00fc\u00dfigkeit in die Hand gedr\u00fcckt und durfte diese an seinen Sitznachbarn weiterschenken. Dazu sollte w\u00e4hrenddessen jeder ein paar nette Worte zu seinen Geschenkpartner sagen und alle h\u00f6rten dabei zu. F\u00fcr viele war das nicht einfach &#8211; wann sagt man denn bitte einfach so vor allen anderen, warum einem sein Sitznachbar wichtig ist, gerade wenn man sonst in ganz anderem Ton miteinander auskommt&#8230; Aber genau das mal aus den Jungs raus zu kitzeln war wirklich sehr sch\u00f6n und hat mir gut getan, sodass ich sp\u00e4testens nach dem typisch-bolivianischen Tortenfestschmaus mit viiel Sahne oben drauf auch endlich einigerma\u00dfen in Feststimmung gekommen bin \ud83d\ude42<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191225-WA0012-576x1024.jpg\" alt=\"\" class=\"wp-image-268\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191225-WA0012-576x1024.jpg 576w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191225-WA0012-169x300.jpg 169w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191225-WA0012.jpg 581w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><figcaption> Weihnachtsfeier im Hogar <a href=\"https:\/\/www.donboscomission.de\/don-bosco\/\">Don Bosco<\/a> <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Nach dieser Bescherung, die ich zum Abschluss noch mit einem saftigen &#8222;Feliz Navidad&#8220; auf der Gitarre begleitet habe, ging es dann in die ebenfalls mit blinkenden Lichterketten, festlich geschm\u00fcckte Kirche des Projekts, um gemeinsam mit allen Einrichtungen zusammen den Weihnachtsgottesdienst zu feiern. Der selber hat sich vom Ablauf tats\u00e4chlich nicht viel von einer Messe wie ich sie so kenne abgehoben. Danach ging es vereint in\u00b4s Hogar Don Bosco, das Kinderheim und zugleich auch die gr\u00f6\u00dfte Einrichtung des Projekts, um dort nochmal richtig zu feiern &#8211; w\u00e4hrend dem Genuss eines leckeren &#8222;pollo&#8220; (irgendein Gefl\u00fcgelbraten) mit Reis und Salat, h\u00f6rte man die hiesige Weihnachtsmusik, schaute sich auf die Leinwand projizierte Weihnachtsgr\u00fc\u00dfe von ehemaligen Volont\u00e4ren aus dem Projekt an und nahm allesamt an der anschlie\u00dfenden Tombola teil, in der der ein oder andere noch ein kleines Geschenk abstauben konnte &#8211; alles in allem &#8211; ein sch\u00f6ner, ausgelassener und mit gutem Essen getoppter Abend, den ich so schnell nicht wieder vergessen werde.  <\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Zwischendurch habe ich mich schon hin und wieder an zu Hause gedacht, wo ja schon f\u00fcnf Stunden fr\u00fcher Bescherung gefeiert wurde&#8230; Um dann nicht allzu melancholisch zu werden, haben wir uns danach als Volont\u00e4re in unseren eigenen vier W\u00e4nden zur\u00fcckgezogen und wunderbar heimisch schmeckenden, selbstgemachten Gl\u00fchwein getrunken und die deutschen Weihnachtsschlager genossen. Das musste der Vollst\u00e4ndigkeit halber dann doch noch sein \ud83d\ude42<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Silvester auch mal ganz anders&#8230;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Am 26. Dezember hatten sich spontan zwei Volont\u00e4rskollegen aus Santiago del Estero (Argentinien) bei uns gemeldet, ob sie uns denn nicht spontan \u00fcber Silvester hier in <a href=\"https:\/\/strassenkinder.de\/laender\/lateinamerika\/bolivien-strassenkinderzentrum\/\">Santa Cruz<\/a> besuchen k\u00f6nnten&#8230; Naja haben wir uns gedacht &#8211; schlimmer geht immer &#8211; wenn die beiden mal eben mal die 30 Stunden Busfahrt auf sich nehmen wollen, sollen sie das doch gerne. Gesagt, getan &#8211; am 30.12. fr\u00fch morgens holte ich die beiden vom Busterminal ab und brachte sie ins Techo, wo sie praktischerweise f\u00fcr die paar Tage untergebracht werden konnten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nat\u00fcrlich hatten unsere Besucher ihren &#8211; f\u00fcr Argentinien absolut obligatorischen &#8222;Mate&#8220; dabei &#8211; ein typisches, einem Tee anmutendem Kr\u00e4uterges\u00f6ff, was man dort so der Gewohn- und Geselligkeit halber mehrere Male am Tag in Gemeinschaft zu sich nimmt. Davon blieben wir w\u00e4hrend ihrer Zeit hier also auch nicht ganz verschont &#8211; und so b\u00fcrgerte sich dieser Brauch auch bei uns Santa Cruz-Volont\u00e4ren ziemlich schnell ein, sodass wir uns hier mittlerweile mit unserem eigenen Equipment ausgestattet haben.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wie viele Mate-Sessions bis zum Silvesterabend vergingen wei\u00df ich ehrlich gesagt nicht mehr&#8230;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230;aber irgendwann war es dann so weit. Bis zum Abend des 31. waren alle in ihrer Einrichtung und a\u00dfen nach der Jahresendmesse noch schmackhaft dort zu Abend &#8211; danach verabschiedeten wir uns vom Projekt, um als Volont\u00e4re mit noch einigen Bekannten Bolivianern in eine Bar mit Silvesterangebot zu gehen, um uns dort vom ereignisreichen 2019 zu verabschieden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das war tats\u00e4chlich ein entspannter und sch\u00f6ner Rutsch ins 2020, bei dem wir Hamburger essend und in Gemeinschaft mit unseren Kollegen aus Argentinien auf irgendeiner Dachterrasse in Santa Cruz das Feuerwerk genossen &#8211; &#8211; &#8211;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Man\nkann dabei noch erw\u00e4hnen, dass die Bolivianer es damit nicht so\ngenau nehmen &#8211; es wurde schon \u00b4ne halbe Minute vor 12 mit dem\nKnallern angefangen und \u00fcbrigens auch an Heiligabend wurde\nmitternachts schon ein riesen-Feuerwerk gestartet.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Gut sind wir angekommen im neuen Jahr! &#8211;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Am 1.1. war man so gn\u00e4dig und hat uns von der &#8222;Arbeit&#8220; freigegeben, sodass wir es ganz &#8222;tranquilo&#8220; &#8211; gelassen &#8211; angehen lie\u00dfen. Am Abend des 2.1. verabschiedeten wir uns dann von unseren zwei Besuchern, mit denen wir ein paar wirklich sch\u00f6ne Tage hier im Projekt und in unserem Volont\u00e4rshaus verbracht haben, die dann ihren <a href=\"https:\/\/multimedia.strassenkinder.de\/bolivien\">Bolivien<\/a>-Reiseurlaub fortgesetzt haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Hier verlinke ich euch noch die Blogs von Martha und Simon, den beiden Volos aus Argentinien:<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Simon: https:\/\/blogs.donboscovolunteers.de\/messimatemerienda\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Martha: https:\/\/blogs.donboscovolunteers.de\/tauschealpengegenanden\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dort erf\u00e4hrt man eine ganze Menge mehr \u00fcber das schon erw\u00e4hnte wohlschmeckende Kr\u00e4uterges\u00f6ff und generell wie es sich als Volont\u00e4r in Argentinien so lebt \ud83d\ude42<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich verabschiede mich jetzt erst mal bis zum n\u00e4chsten Mal &#8211; macht\u00b4s alle gut und bis dann &#8211;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191226-WA0011-505x1024.jpg\" alt=\"\" class=\"wp-image-269\" width=\"424\" height=\"859\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191226-WA0011-505x1024.jpg 505w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191226-WA0011-148x300.jpg 148w, https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191226-WA0011.jpg 631w\" sizes=\"auto, (max-width: 424px) 100vw, 424px\" \/><figcaption>Ach ja &#8211; da war ja noch was&#8230;<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Euer\nGabriel<\/p>","protected":false},"excerpt":{"rendered":"<p>Guten morgen, guten Mittag oder auch guten Abend liebe Leute, &#8230;mag sein, dass die Weihnachtszeit nun schon etwas her ist, aber daf\u00fcr bekommt ihr jetzt einen kleinen Einblick, wie man das Ganze hier in S\u00fcdamerika feiert. Ich wei\u00df gar nicht mehr, ob und wem ich w\u00e4hrend der Vorweihnachtszeit alles schon erz\u00e4hlt habe, in wie wenig [&hellip;]<\/p>\n","protected":false},"author":21652,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,29],"tags":[22,42,34,41],"class_list":["post-263","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-im-projekt-vor-ort","tag-proyecto-don-bosco","tag-silvester","tag-volontaere","tag-weihnachten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weihnachtszeit und Neujahr - ich erz\u00e4hle euch mal wie das so war. - Ich bin dann mal raus von zu Haus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weihnachtszeit und Neujahr - ich erz\u00e4hle euch mal wie das so war. - Ich bin dann mal raus von zu Haus\" \/>\n<meta property=\"og:description\" content=\"Guten morgen, guten Mittag oder auch guten Abend liebe Leute, &#8230;mag sein, dass die Weihnachtszeit nun schon etwas her ist, aber daf\u00fcr bekommt ihr jetzt einen kleinen Einblick, wie man das Ganze hier in S\u00fcdamerika feiert. Ich wei\u00df gar nicht mehr, ob und wem ich w\u00e4hrend der Vorweihnachtszeit alles schon erz\u00e4hlt habe, in wie wenig [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/\" \/>\n<meta property=\"og:site_name\" content=\"Ich bin dann mal raus von zu Haus\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-17T18:44:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-17T18:47:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191211-WA0004-1024x768.jpg\" \/>\n<meta name=\"author\" content=\"Gabriel Booms\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Booms\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/01\\\/17\\\/weihnachtszeit-und-neujahr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/01\\\/17\\\/weihnachtszeit-und-neujahr\\\/\"},\"author\":{\"name\":\"Gabriel Booms\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/#\\\/schema\\\/person\\\/1a683864941695e1f0cc7bf11766a30a\"},\"headline\":\"Weihnachtszeit und Neujahr &#8211; ich erz\u00e4hle euch mal wie das so war.\",\"datePublished\":\"2020-01-17T18:44:03+00:00\",\"dateModified\":\"2020-01-17T18:47:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/01\\\/17\\\/weihnachtszeit-und-neujahr\\\/\"},\"wordCount\":1262,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/01\\\/17\\\/weihnachtszeit-und-neujahr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/wp-content\\\/uploads\\\/sites\\\/21591\\\/2020\\\/01\\\/IMG-20191211-WA0004-1024x768.jpg\",\"keywords\":[\"Proyecto Don Bosco\",\"Silvester\",\"Volont\u00e4re\",\"Weihnachten\"],\"articleSection\":{\"1\":\"Im Projekt vor Ort\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/01\\\/17\\\/weihnachtszeit-und-neujahr\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/01\\\/17\\\/weihnachtszeit-und-neujahr\\\/\",\"url\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/01\\\/17\\\/weihnachtszeit-und-neujahr\\\/\",\"name\":\"Weihnachtszeit und Neujahr - ich erz\u00e4hle euch mal wie das so war. - Ich bin dann mal raus von zu Haus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/01\\\/17\\\/weihnachtszeit-und-neujahr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/01\\\/17\\\/weihnachtszeit-und-neujahr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/wp-content\\\/uploads\\\/sites\\\/21591\\\/2020\\\/01\\\/IMG-20191211-WA0004-1024x768.jpg\",\"datePublished\":\"2020-01-17T18:44:03+00:00\",\"dateModified\":\"2020-01-17T18:47:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/#\\\/schema\\\/person\\\/1a683864941695e1f0cc7bf11766a30a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/01\\\/17\\\/weihnachtszeit-und-neujahr\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/01\\\/17\\\/weihnachtszeit-und-neujahr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/01\\\/17\\\/weihnachtszeit-und-neujahr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/wp-content\\\/uploads\\\/sites\\\/21591\\\/2020\\\/01\\\/IMG-20191211-WA0004.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/wp-content\\\/uploads\\\/sites\\\/21591\\\/2020\\\/01\\\/IMG-20191211-WA0004.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/2020\\\/01\\\/17\\\/weihnachtszeit-und-neujahr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weihnachtszeit und Neujahr &#8211; ich erz\u00e4hle euch mal wie das so war.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/#website\",\"url\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/\",\"name\":\"Ich bin dann mal raus von zu Haus\",\"description\":\"Ein Jahr in Bolivien\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/#\\\/schema\\\/person\\\/1a683864941695e1f0cc7bf11766a30a\",\"name\":\"Gabriel Booms\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92e27b1059f2d1de2c41fd06a37662ca44a4fa61c443eab6be7a8ead5e3d9b62?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92e27b1059f2d1de2c41fd06a37662ca44a4fa61c443eab6be7a8ead5e3d9b62?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92e27b1059f2d1de2c41fd06a37662ca44a4fa61c443eab6be7a8ead5e3d9b62?s=96&d=blank&r=g\",\"caption\":\"Gabriel Booms\"},\"description\":\"Buenos dias, Guten Tag oder Servus zusammen! Ich bin Gabriel Booms, 18 Jahre jung und fliege am 1. September 2019 f\u00fcr ein Jahr nach Santa Cruz de la Sierra in Bolivien. Das hier ist mein pers\u00f6nlicher Blog, in dem ich euch gerne hin und wieder mit frischen Neuigkeiten aus meinem Projekt in Bolivien versorgen m\u00f6chte. Wer gerne direkt mitbekommen will, wenn ich hier was poste, schreibt mir doch einfach einen Kommentar mit seiner E-Mail Adresse - dann nehme ich euch gerne in meinen Verteiler auf. Sch\u00f6n, dass ihr dabei seit - Euer Gabriel\",\"url\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/gabibolivien\\\/author\\\/bolivibooms\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weihnachtszeit und Neujahr - ich erz\u00e4hle euch mal wie das so war. - Ich bin dann mal raus von zu Haus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/","og_locale":"de_DE","og_type":"article","og_title":"Weihnachtszeit und Neujahr - ich erz\u00e4hle euch mal wie das so war. - Ich bin dann mal raus von zu Haus","og_description":"Guten morgen, guten Mittag oder auch guten Abend liebe Leute, &#8230;mag sein, dass die Weihnachtszeit nun schon etwas her ist, aber daf\u00fcr bekommt ihr jetzt einen kleinen Einblick, wie man das Ganze hier in S\u00fcdamerika feiert. Ich wei\u00df gar nicht mehr, ob und wem ich w\u00e4hrend der Vorweihnachtszeit alles schon erz\u00e4hlt habe, in wie wenig [&hellip;]","og_url":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/","og_site_name":"Ich bin dann mal raus von zu Haus","article_published_time":"2020-01-17T18:44:03+00:00","article_modified_time":"2020-01-17T18:47:31+00:00","og_image":[{"url":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191211-WA0004-1024x768.jpg","type":"","width":"","height":""}],"author":"Gabriel Booms","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Gabriel Booms","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/#article","isPartOf":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/"},"author":{"name":"Gabriel Booms","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/#\/schema\/person\/1a683864941695e1f0cc7bf11766a30a"},"headline":"Weihnachtszeit und Neujahr &#8211; ich erz\u00e4hle euch mal wie das so war.","datePublished":"2020-01-17T18:44:03+00:00","dateModified":"2020-01-17T18:47:31+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/"},"wordCount":1262,"commentCount":1,"image":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191211-WA0004-1024x768.jpg","keywords":["Proyecto Don Bosco","Silvester","Volont\u00e4re","Weihnachten"],"articleSection":{"1":"Im Projekt vor Ort"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/","url":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/","name":"Weihnachtszeit und Neujahr - ich erz\u00e4hle euch mal wie das so war. - Ich bin dann mal raus von zu Haus","isPartOf":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/#primaryimage"},"image":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191211-WA0004-1024x768.jpg","datePublished":"2020-01-17T18:44:03+00:00","dateModified":"2020-01-17T18:47:31+00:00","author":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/#\/schema\/person\/1a683864941695e1f0cc7bf11766a30a"},"breadcrumb":{"@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/#primaryimage","url":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191211-WA0004.jpg","contentUrl":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-content\/uploads\/sites\/21591\/2020\/01\/IMG-20191211-WA0004.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/2020\/01\/17\/weihnachtszeit-und-neujahr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/"},{"@type":"ListItem","position":2,"name":"Weihnachtszeit und Neujahr &#8211; ich erz\u00e4hle euch mal wie das so war."}]},{"@type":"WebSite","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/#website","url":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/","name":"Ich bin dann mal raus von zu Haus","description":"Ein Jahr in Bolivien","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/#\/schema\/person\/1a683864941695e1f0cc7bf11766a30a","name":"Gabriel Booms","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/92e27b1059f2d1de2c41fd06a37662ca44a4fa61c443eab6be7a8ead5e3d9b62?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/92e27b1059f2d1de2c41fd06a37662ca44a4fa61c443eab6be7a8ead5e3d9b62?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/92e27b1059f2d1de2c41fd06a37662ca44a4fa61c443eab6be7a8ead5e3d9b62?s=96&d=blank&r=g","caption":"Gabriel Booms"},"description":"Buenos dias, Guten Tag oder Servus zusammen! Ich bin Gabriel Booms, 18 Jahre jung und fliege am 1. September 2019 f\u00fcr ein Jahr nach Santa Cruz de la Sierra in Bolivien. Das hier ist mein pers\u00f6nlicher Blog, in dem ich euch gerne hin und wieder mit frischen Neuigkeiten aus meinem Projekt in Bolivien versorgen m\u00f6chte. Wer gerne direkt mitbekommen will, wenn ich hier was poste, schreibt mir doch einfach einen Kommentar mit seiner E-Mail Adresse - dann nehme ich euch gerne in meinen Verteiler auf. Sch\u00f6n, dass ihr dabei seit - Euer Gabriel","url":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/author\/bolivibooms\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/posts\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/users\/21652"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":8,"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/posts\/263\/revisions"}],"predecessor-version":[{"id":279,"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/posts\/263\/revisions\/279"}],"wp:attachment":[{"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/media?parent=263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/categories?post=263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.donboscovolunteers.de\/gabibolivien\/wp-json\/wp\/v2\/tags?post=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}