{"id":333,"date":"2018-06-16T14:56:25","date_gmt":"2018-06-16T12:56:25","guid":{"rendered":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/?p=333"},"modified":"2018-06-16T21:53:00","modified_gmt":"2018-06-16T19:53:00","slug":"typisch-albanisch","status":"publish","type":"post","link":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/","title":{"rendered":",,Typisch Albanisch&#8220;"},"content":{"rendered":"<p>Aufgrund einer Halsentz\u00fcndung hatte ich etwas mehr Zeit in den letzten Tagen, um einen neuen Blogeintrag zu verfassen, der mir schon wieder seit mindestens einem Monat im Kopf herumschwirrt.<\/p>\n<p>Und zwar m\u00f6chte ich einmal auf die albanische Kultur und was denn so ,,typisch albanisch&#8220; ist, eingehen. Nat\u00fcrlich sind alles nur die Eindr\u00fccke, die ich den mittlerweile 10 Monaten hier gesammelt haben und die selbstverst\u00e4ndlich nicht auf alle Albaner zu \u00fcbertragen, aber einfach Dinge, die mir aufgefallen sind.<\/p>\n<p><strong>Direktheit <\/strong><\/p>\n<p>Die Albaner sind immer direkt, so bekommt man h\u00e4ufig zu h\u00f6ren: ,,Oh dein Outfit ist aber sch\u00f6n.&#8220; ,,Du siehst heute so sch\u00f6n aus.&#8220; ,,Du bist so s\u00fc\u00df.&#8220; ,,Du bist so flei\u00dfig und hilfst immer so gut.&#8220; Mindestens genauso oft h\u00f6rt man dann aber auch wieder ,,Bist du krank? Du siehst heute echt schlecht aus&#8220; &#8211; Was soll ich sagen? Ich war nat\u00fcrlich nicht krank&#8230; \ud83d\ude00 Oder man macht Witze \u00fcber die Akne, die Figur oder \u00fcber diejenigen, die etwas br\u00e4unere Haut haben. Auch meine 2 Freunde, Volont\u00e4re aus der Schweiz und Deutschland haben nicht schlecht gestaunt, als ihnen ihre Mitarbeiter gesagt habe, dass sie fett geworden seien. Die Albaner sind einfach direkt und nehmen kein Blatt vor den Mund. Meiner Meinung gleicht sich das ganze gut aus, da man viele Komplimente bekommt und mit der Zeit nimmt das Ganze auch nicht mehr so ernst, denn wenn es etwas, dass alle gerne tun, dann ist das \u00fcbertreiben.<\/p>\n<p><strong>L\u00e4stern &#8211; das beliebteste Hobby<\/strong><\/p>\n<p>Noch lieber als jemandem ins Gesicht zu sagen, ist das Ganze hinter dem R\u00fccken zu machen. So wird oft beim stundenlangen Kaffeetrinken \u00fcber das neueste Outfit jemandes geredet, denn alle kennen oder vielleicht \u00fcber die etwas fragw\u00fcrdige Frisur eines v\u00f6llig unbekanntem Passanten. Oft wird mir gesagt ,,Ach es w\u00e4re sch\u00f6n in einem anderen Land zu leben, wo man einfach tun kann, was man will.&#8220; Hier wird einfach immer dar\u00fcber geredet und man m\u00f6chte ja sich und seine Familie nicht schlecht hinstellen. Auch in Deutschland wird \u00fcber andere geredet und der neueste Tratsch ausgetauscht, ich denke das liegt in der menschlichen Natur, dadurch, dass hier einiges noch traditioneller ist und etwas anders abl\u00e4uft in Deutschland, wird zum Beispiel auch unter den Nachbarn getratscht, wen man denn nach Hause bringt, dennoch finde ich es hier etwas ausgepr\u00e4gter.<\/p>\n<p><strong>Kaffeekultur<\/strong><\/p>\n<p>Das Kaffeetrinken geh\u00f6rt hier einfach zum Leben, schlie\u00dflich macht man eigentlich fast nichts anderes als in ein Caf\u00e9 zu gehen, wenn man sich mit Freunden trifft. Dabei wird starker t\u00fcrkischer Kaffee getrunken. Das Kaffeetrinken wurde zu einem wirklich ausgepr\u00e4gtem Hobby f\u00fcr mich, fast t\u00e4glich treffe ich mich dazu mit Freunden, man bleibt gerne stundenlang sitzen und redet (oder tauscht sich \u00fcber den n\u00e4chsten Tratsch aus, wie bereits erw\u00e4hnt.) Warum das Kaffeetrinken hier so popul\u00e4r ist? Es gibt hier einfach nicht so viele M\u00f6glichkeiten etwas zu machen, der Kaffee mit 50 Cent pro Tasse ist wenigstens preisg\u00fcnstig. Auch trifft man sich nicht unbedingt zu Hause bei anderen, man bringt niemand Fremdes nach Hause, au\u00dferdem sind die Wohnungen h\u00e4ufig sehr klein, die Zimmer werden sich immer unter den Kindern geteilt, teilweise auch mit Gro\u00dfeltern etc.<\/p>\n<p><strong>Gesundheitssystem<\/strong><\/p>\n<p>Aufgrund meiner mittlerweile vergangenen Krankheit, hatte ich auch die M\u00f6glichkeit in das Gesundheitssystem einblicken zu k\u00f6nnen. Nat\u00fcrlich war es nicht sch\u00f6n so krank zu sein, dennoch finde ich, dies war eine bereichernde Erfahrung, als ich n\u00e4mlich entdeckt habe, dass sich in meinem wirklich sehr geschwollenem Hals mittlerweile auch Eiter gebildet hat, wusste ich es handele sich leider nicht mehr um harmlose Halsschmerzen und das ich mich vielleicht doch zum Arzt begeben sollte. Deswegen habe ich dann dem wohlgemerkt ,,besten&#8220; Krankenhaus der Stadt abgestattet. Naja vom Aussehen schien es mir schon sehr unterschiedlich zu Deutschland, aber die Schwestern und die \u00c4rztin waren supernett, haben sich ganz lieb um mich gek\u00fcmmert und die ganze Behandlung war umsonst. Nat\u00fcrlich w\u00e4re das kein Problem f\u00fcr mich und ich bin in meinem <a href=\"https:\/\/www.donboscovolunteers.de\/\">Freiwilligendienst<\/a> auch versichert, aber ich finde es gut zu wissen, dass die Menschen dorthin gehen k\u00f6nnen, auch wenn sie kein Geld haben, denn das ganze finanziert der Staat. Die Medikamente musste ich dann schon bezahlen. Also ich pers\u00f6nlich habe keine schlechten Erfahrungen gemacht, ich habe allerdings schon Geschichten von Fahrr\u00e4dern im OP-Saal geh\u00f6rt, denn drau\u00dfen wird es ja gestohlen&#8230;<\/p>\n<p><strong>Religion<\/strong><\/p>\n<p>Wie schon oft erw\u00e4hnt ist der Glaube hier so wichtig f\u00fcr viele Menschen. Sonntags geht man in die Kirche egal welchen Alters. Aber was ich am sch\u00f6nsten hier finde, dass es Christen und Muslime sich hier so gut tolerieren. Auch ins Oratori kommen t\u00e4glich viele Muslime, wir beten dort oft zusammen, aber das wird von den muslimischen Kindern toleriert, genauso wurde gestern aufgrund des Bayrams (Ende des Ramadans) ein freier Tag der Summergames, die mittlerweile begonnen haben, eingelegt.<\/p>\n<p><strong>Herzlichkeit<\/strong><\/p>\n<p>Auch die Herzlichkeit habe ich schon in vielen vorangegangen Blogeintr\u00e4gen erw\u00e4hnt, m\u00f6chte sie nun aber noch einmal aufgreifen, da sie einfache zum ,,typischen&#8220; Albanerdasein dazugeh\u00f6rt. Man erkundigt sich immer freundlich wie es den anderen geht, auch die zahlreiche K\u00fcsschenverteilung, spricht meiner Meinung nach daf\u00fcr. Man wird \u00fcberall mit offenen Armen empfangen und vor allem als Ausl\u00e4nder wird man h\u00e4ufig eingeladen, auch wenn die Menschen vielleicht nicht so viel Geld haben, aber man kann sie nicht davon abbringen.<\/p>\n<p><strong>Tradition<\/strong><\/p>\n<p>Die Albaner sind sehr traditionsbewusst, zum Einen der albanischen Kultur mit den T\u00e4nzen, der Musik, aber auch beispielsweise beim Essen bleiben sie traditionell. Es gibt hier ein Sushi Restaurant in Shkodra, als ich dort zusammen mit einer Freundin war, wurden wir tagelang ausgefragt, wie es denn war und das Ganze wurde kritisch begutachtet. Genauso ergeht es mir jedesmal, wenn ich sage, dass ich Kontaktlinsen trage. Diese Dinge sind ,,moderner&#8220; und sind nicht seit Jahrzehnten in Gebrauch, deswegen fehlt das Vertrauen darin. Auch beispielsweise Tampons werden aus diesem und aus religi\u00f6sen Gr\u00fcnden nicht gebraucht hier. Zur Tradition geh\u00f6rt es auch, fr\u00fch zu heiraten, die Familie steht an oberster Stelle. Die Frau wird nach der Hochzeit eine typische Hausfrau, kocht, k\u00fcmmert sich um die Kinder und putzt das Haus. Aus diesem Grund finde ich es sehr wichtig, dass die Jungs hier im Haus auch mithelfen m\u00fcssen, beim Teller abtrocknen, zusammenkehren etc.<\/p>\n<p>Viele verbinden Albanien mit Kriminalit\u00e4t und der Mafia, dies sind Ger\u00fcchte oder Stereotypen, so wie die deutsche P\u00fcnktlichkeit oder dass alle Deutschen Bier lieben. Es gibt f\u00fcr alle L\u00e4nder diese Stereotypen, die es aber gilt zu durchschauen. Dies sind nun meine Eindr\u00fccke aus meiner Sicht und meinem Umfeld.<\/p>\n<p>&nbsp;<\/p>\n<p>Des Weiteren haben mittlerweile die Sommerferien und somit die Sommerspiele begonnen. Im Haus ist es ruhig, bis auf ein paar Ausnahmen sind alle Jungs zu Hause und kommen erst wieder im September, was f\u00fcr mich schon den endg\u00fcltigen Abschied f\u00fcr sie hei\u00dft. Langweilig wird mir aber erstmal nicht dank der Sommerspiele, die einigen Schwung in das Oratori bringt. Bald folgt ein Eintrag dar\u00fcber.<\/p>\n<p>Hier noch ein paar Eindr\u00fccke von einem Ausflug, den ich zusammen mit den Animatoren des Oratoris gemacht habe. Dabei hatte ich das Vergn\u00fcgen den S\u00fcden Albaniens erkunden zu k\u00f6nnen, der wahre Schatz Albaniens. Ich war wirklich begeistert von den Orten, die wir besucht haben, vor allem von den sch\u00f6nen Str\u00e4nden und dem Meer.<\/p>\n<p><a href=\"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG_20180603_171405.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-337 size-medium\" src=\"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG_20180603_171405-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG_20180603_171405-300x225.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG_20180603_171405-768x576.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG_20180603_171405-1024x768.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG_20180603_171405-900x675.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG_20180603_171405.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG-20180604-WA0000.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-338 size-medium\" src=\"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG-20180604-WA0000-169x300.jpg\" alt=\"\" width=\"169\" height=\"300\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG-20180604-WA0000-169x300.jpg 169w, https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG-20180604-WA0000-576x1024.jpg 576w, https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG-20180604-WA0000.jpg 720w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a> <a href=\"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG-20180605-WA0001.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-339 size-medium\" src=\"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG-20180605-WA0001-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG-20180605-WA0001-300x225.jpg 300w, https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG-20180605-WA0001-768x576.jpg 768w, https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG-20180605-WA0001-1024x768.jpg 1024w, https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG-20180605-WA0001-900x675.jpg 900w, https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/IMG-20180605-WA0001.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aufgrund einer Halsentz\u00fcndung hatte ich etwas mehr Zeit in den letzten Tagen, um einen neuen Blogeintrag zu verfassen, der mir schon wieder seit mindestens einem Monat im Kopf herumschwirrt. Und zwar m\u00f6chte ich einmal auf die albanische Kultur und was denn so ,,typisch albanisch&#8220; ist, eingehen. Nat\u00fcrlich sind alles nur die Eindr\u00fccke, die ich den [&hellip;]<\/p>\n","protected":false},"author":21536,"featured_media":336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>,,Typisch Albanisch&#039;&#039; - Emilia in Albanien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\",,Typisch Albanisch&#039;&#039; - Emilia in Albanien\" \/>\n<meta property=\"og:description\" content=\"Aufgrund einer Halsentz\u00fcndung hatte ich etwas mehr Zeit in den letzten Tagen, um einen neuen Blogeintrag zu verfassen, der mir schon wieder seit mindestens einem Monat im Kopf herumschwirrt. Und zwar m\u00f6chte ich einmal auf die albanische Kultur und was denn so ,,typisch albanisch&#8220; ist, eingehen. Nat\u00fcrlich sind alles nur die Eindr\u00fccke, die ich den [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/\" \/>\n<meta property=\"og:site_name\" content=\"Emilia in Albanien\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-16T12:56:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-16T19:53:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/gjirokaster.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emilia Haimerl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emilia Haimerl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/2018\\\/06\\\/16\\\/typisch-albanisch\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/2018\\\/06\\\/16\\\/typisch-albanisch\\\/\"},\"author\":{\"name\":\"Emilia Haimerl\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/#\\\/schema\\\/person\\\/0d6b3027de83108803c79156dd67e346\"},\"headline\":\",,Typisch Albanisch&#8220;\",\"datePublished\":\"2018-06-16T12:56:25+00:00\",\"dateModified\":\"2018-06-16T19:53:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/2018\\\/06\\\/16\\\/typisch-albanisch\\\/\"},\"wordCount\":1259,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/2018\\\/06\\\/16\\\/typisch-albanisch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/wp-content\\\/uploads\\\/sites\\\/21485\\\/2018\\\/06\\\/gjirokaster.jpg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/2018\\\/06\\\/16\\\/typisch-albanisch\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/2018\\\/06\\\/16\\\/typisch-albanisch\\\/\",\"url\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/2018\\\/06\\\/16\\\/typisch-albanisch\\\/\",\"name\":\",,Typisch Albanisch'' - Emilia in Albanien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/2018\\\/06\\\/16\\\/typisch-albanisch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/2018\\\/06\\\/16\\\/typisch-albanisch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/wp-content\\\/uploads\\\/sites\\\/21485\\\/2018\\\/06\\\/gjirokaster.jpg\",\"datePublished\":\"2018-06-16T12:56:25+00:00\",\"dateModified\":\"2018-06-16T19:53:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/#\\\/schema\\\/person\\\/0d6b3027de83108803c79156dd67e346\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/2018\\\/06\\\/16\\\/typisch-albanisch\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/2018\\\/06\\\/16\\\/typisch-albanisch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/2018\\\/06\\\/16\\\/typisch-albanisch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/wp-content\\\/uploads\\\/sites\\\/21485\\\/2018\\\/06\\\/gjirokaster.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/wp-content\\\/uploads\\\/sites\\\/21485\\\/2018\\\/06\\\/gjirokaster.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/2018\\\/06\\\/16\\\/typisch-albanisch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\",,Typisch Albanisch&#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/#website\",\"url\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/\",\"name\":\"Emilia in Albanien\",\"description\":\"365 Tage volunteering\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/#\\\/schema\\\/person\\\/0d6b3027de83108803c79156dd67e346\",\"name\":\"Emilia Haimerl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d6f38376f21db83553a40fe7cb3632295f24b05e9beaff7a0591aa7872cf5e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d6f38376f21db83553a40fe7cb3632295f24b05e9beaff7a0591aa7872cf5e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0d6f38376f21db83553a40fe7cb3632295f24b05e9beaff7a0591aa7872cf5e?s=96&d=mm&r=g\",\"caption\":\"Emilia Haimerl\"},\"description\":\"Ich bin Emilia Haimerl, bin 18 Jahre alt und komme aus Plattling, einer Kleinstadt in Niederbayern. Dieses Jahr habe ich mein Abitur am St.-Gotthard- Gymnasium Niederalteich, gemacht und nun geht es bald los f\u00fcr mich, denn ich habe beschlossen ab September 2017 einen Freiwilligendienst mit den Salesianern Don Boscos zu machen. (Mehr Infos dazu unter http:\\\/\\\/www.donboscovolunteers.de\\\/) Dabei werde ich f\u00fcr ein Jahr in Shkoder, Albanien, leben, dort in einer Einrichtung der Salesianer Don Boscos arbeiten und meine ganze Aufmerksamkeit den Kindern und Jugendlichen vor Ort widmen. Bis jetzt war ich in der Kinder- und Jugendarbeit in meiner Heimatpfarrei St. Magdalena in Plattling t\u00e4tig. Ich freue mich jetzt schon auf alle Erfahrungen und die Kinder und Jugendlichen vor Ort und werde in K\u00fcrze dar\u00fcber auf meinem Blog berichten. Liebe Gr\u00fc\u00dfe, Emilia\",\"url\":\"https:\\\/\\\/blogs.donboscovolunteers.de\\\/emiliainalbanien\\\/author\\\/emilia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":",,Typisch Albanisch'' - Emilia in Albanien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/","og_locale":"de_DE","og_type":"article","og_title":",,Typisch Albanisch'' - Emilia in Albanien","og_description":"Aufgrund einer Halsentz\u00fcndung hatte ich etwas mehr Zeit in den letzten Tagen, um einen neuen Blogeintrag zu verfassen, der mir schon wieder seit mindestens einem Monat im Kopf herumschwirrt. Und zwar m\u00f6chte ich einmal auf die albanische Kultur und was denn so ,,typisch albanisch&#8220; ist, eingehen. Nat\u00fcrlich sind alles nur die Eindr\u00fccke, die ich den [&hellip;]","og_url":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/","og_site_name":"Emilia in Albanien","article_published_time":"2018-06-16T12:56:25+00:00","article_modified_time":"2018-06-16T19:53:00+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/gjirokaster.jpg","type":"image\/jpeg"}],"author":"Emilia Haimerl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Emilia Haimerl","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/#article","isPartOf":{"@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/"},"author":{"name":"Emilia Haimerl","@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/#\/schema\/person\/0d6b3027de83108803c79156dd67e346"},"headline":",,Typisch Albanisch&#8220;","datePublished":"2018-06-16T12:56:25+00:00","dateModified":"2018-06-16T19:53:00+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/"},"wordCount":1259,"commentCount":0,"image":{"@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/gjirokaster.jpg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/","url":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/","name":",,Typisch Albanisch'' - Emilia in Albanien","isPartOf":{"@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/#primaryimage"},"image":{"@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/gjirokaster.jpg","datePublished":"2018-06-16T12:56:25+00:00","dateModified":"2018-06-16T19:53:00+00:00","author":{"@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/#\/schema\/person\/0d6b3027de83108803c79156dd67e346"},"breadcrumb":{"@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/#primaryimage","url":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/gjirokaster.jpg","contentUrl":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-content\/uploads\/sites\/21485\/2018\/06\/gjirokaster.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/2018\/06\/16\/typisch-albanisch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/"},{"@type":"ListItem","position":2,"name":",,Typisch Albanisch&#8220;"}]},{"@type":"WebSite","@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/#website","url":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/","name":"Emilia in Albanien","description":"365 Tage volunteering","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/#\/schema\/person\/0d6b3027de83108803c79156dd67e346","name":"Emilia Haimerl","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a0d6f38376f21db83553a40fe7cb3632295f24b05e9beaff7a0591aa7872cf5e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a0d6f38376f21db83553a40fe7cb3632295f24b05e9beaff7a0591aa7872cf5e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a0d6f38376f21db83553a40fe7cb3632295f24b05e9beaff7a0591aa7872cf5e?s=96&d=mm&r=g","caption":"Emilia Haimerl"},"description":"Ich bin Emilia Haimerl, bin 18 Jahre alt und komme aus Plattling, einer Kleinstadt in Niederbayern. Dieses Jahr habe ich mein Abitur am St.-Gotthard- Gymnasium Niederalteich, gemacht und nun geht es bald los f\u00fcr mich, denn ich habe beschlossen ab September 2017 einen Freiwilligendienst mit den Salesianern Don Boscos zu machen. (Mehr Infos dazu unter http:\/\/www.donboscovolunteers.de\/) Dabei werde ich f\u00fcr ein Jahr in Shkoder, Albanien, leben, dort in einer Einrichtung der Salesianer Don Boscos arbeiten und meine ganze Aufmerksamkeit den Kindern und Jugendlichen vor Ort widmen. Bis jetzt war ich in der Kinder- und Jugendarbeit in meiner Heimatpfarrei St. Magdalena in Plattling t\u00e4tig. Ich freue mich jetzt schon auf alle Erfahrungen und die Kinder und Jugendlichen vor Ort und werde in K\u00fcrze dar\u00fcber auf meinem Blog berichten. Liebe Gr\u00fc\u00dfe, Emilia","url":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/author\/emilia\/"}]}},"_links":{"self":[{"href":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-json\/wp\/v2\/posts\/333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-json\/wp\/v2\/users\/21536"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-json\/wp\/v2\/comments?post=333"}],"version-history":[{"count":5,"href":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-json\/wp\/v2\/posts\/333\/revisions"}],"predecessor-version":[{"id":342,"href":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-json\/wp\/v2\/posts\/333\/revisions\/342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-json\/wp\/v2\/media\/336"}],"wp:attachment":[{"href":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-json\/wp\/v2\/media?parent=333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-json\/wp\/v2\/categories?post=333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.donboscovolunteers.de\/emiliainalbanien\/wp-json\/wp\/v2\/tags?post=333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}